{"id":5989,"count":1,"description":"","link":"https:\/\/readfi.news\/en\/tag\/%e5%8f%b0%e7%81%a3%e4%ba%ba%e5%a3%bd%e4%bf%9d%e9%9a%aa%e8%82%a1%e4%bb%bd%e6%9c%89%e9%99%90%e5%85%ac%e5%8f%b8\/","name":"\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8","slug":"%e5%8f%b0%e7%81%a3%e4%ba%ba%e5%a3%bd%e4%bf%9d%e9%9a%aa%e8%82%a1%e4%bb%bd%e6%9c%89%e9%99%90%e5%85%ac%e5%8f%b8","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8 - \u5353\u8d8a\u96fb\u5b50\u5831<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/readfi.news\/en\/tag\/\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8 - \u5353\u8d8a\u96fb\u5b50\u5831\" \/>\n<meta property=\"og:url\" content=\"https:\/\/readfi.news\/en\/tag\/\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8\/\" \/>\n<meta property=\"og:site_name\" content=\"\u5353\u8d8a\u96fb\u5b50\u5831\" \/>\n<meta property=\"og:image\" content=\"https:\/\/readfi.news\/wp-content\/uploads\/2022\/09\/S__356565003.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/readfi.news\\\/tag\\\/%e5%8f%b0%e7%81%a3%e4%ba%ba%e5%a3%bd%e4%bf%9d%e9%9a%aa%e8%82%a1%e4%bb%bd%e6%9c%89%e9%99%90%e5%85%ac%e5%8f%b8\\\/\",\"url\":\"https:\\\/\\\/readfi.news\\\/tag\\\/%e5%8f%b0%e7%81%a3%e4%ba%ba%e5%a3%bd%e4%bf%9d%e9%9a%aa%e8%82%a1%e4%bb%bd%e6%9c%89%e9%99%90%e5%85%ac%e5%8f%b8\\\/\",\"name\":\"\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8 - \u5353\u8d8a\u96fb\u5b50\u5831\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/readfi.news\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/readfi.news\\\/tag\\\/%e5%8f%b0%e7%81%a3%e4%ba%ba%e5%a3%bd%e4%bf%9d%e9%9a%aa%e8%82%a1%e4%bb%bd%e6%9c%89%e9%99%90%e5%85%ac%e5%8f%b8\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/readfi.news\\\/tag\\\/%e5%8f%b0%e7%81%a3%e4%ba%ba%e5%a3%bd%e4%bf%9d%e9%9a%aa%e8%82%a1%e4%bb%bd%e6%9c%89%e9%99%90%e5%85%ac%e5%8f%b8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\\\/\\\/readfi.news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/readfi.news\\\/#website\",\"url\":\"https:\\\/\\\/readfi.news\\\/\",\"name\":\"\u5353\u8d8a\u96fb\u5b50\u5831\",\"description\":\"\u8ffd\u6c42\u5dd4\u5cf0\u3001\u5353\u8d8a\u8d85\u7136\",\"publisher\":{\"@id\":\"https:\\\/\\\/readfi.news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/readfi.news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/readfi.news\\\/#organization\",\"name\":\"\u5353\u8d8a\u96fb\u5b50\u5831\",\"url\":\"https:\\\/\\\/readfi.news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/readfi.news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/readfi.news\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/readfi.news\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.jpg\",\"width\":880,\"height\":322,\"caption\":\"\u5353\u8d8a\u96fb\u5b50\u5831\"},\"image\":{\"@id\":\"https:\\\/\\\/readfi.news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/readfi.news\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8 - \u5353\u8d8a\u96fb\u5b50\u5831","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/readfi.news\/en\/tag\/\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8\/","og_locale":"en_US","og_type":"article","og_title":"\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8 - \u5353\u8d8a\u96fb\u5b50\u5831","og_url":"https:\/\/readfi.news\/en\/tag\/\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8\/","og_site_name":"\u5353\u8d8a\u96fb\u5b50\u5831","og_image":[{"width":756,"height":710,"url":"https:\/\/readfi.news\/wp-content\/uploads\/2022\/09\/S__356565003.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/readfi.news\/tag\/%e5%8f%b0%e7%81%a3%e4%ba%ba%e5%a3%bd%e4%bf%9d%e9%9a%aa%e8%82%a1%e4%bb%bd%e6%9c%89%e9%99%90%e5%85%ac%e5%8f%b8\/","url":"https:\/\/readfi.news\/tag\/%e5%8f%b0%e7%81%a3%e4%ba%ba%e5%a3%bd%e4%bf%9d%e9%9a%aa%e8%82%a1%e4%bb%bd%e6%9c%89%e9%99%90%e5%85%ac%e5%8f%b8\/","name":"\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8 - \u5353\u8d8a\u96fb\u5b50\u5831","isPartOf":{"@id":"https:\/\/readfi.news\/#website"},"breadcrumb":{"@id":"https:\/\/readfi.news\/tag\/%e5%8f%b0%e7%81%a3%e4%ba%ba%e5%a3%bd%e4%bf%9d%e9%9a%aa%e8%82%a1%e4%bb%bd%e6%9c%89%e9%99%90%e5%85%ac%e5%8f%b8\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/readfi.news\/tag\/%e5%8f%b0%e7%81%a3%e4%ba%ba%e5%a3%bd%e4%bf%9d%e9%9a%aa%e8%82%a1%e4%bb%bd%e6%9c%89%e9%99%90%e5%85%ac%e5%8f%b8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/readfi.news\/"},{"@type":"ListItem","position":2,"name":"\u53f0\u7063\u4eba\u58fd\u4fdd\u96aa\u80a1\u4efd\u6709\u9650\u516c\u53f8"}]},{"@type":"WebSite","@id":"https:\/\/readfi.news\/#website","url":"https:\/\/readfi.news\/","name":"\u5353\u8d8a\u96fb\u5b50\u5831","description":"\u8ffd\u6c42\u5dd4\u5cf0\u3001\u5353\u8d8a\u8d85\u7136","publisher":{"@id":"https:\/\/readfi.news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/readfi.news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/readfi.news\/#organization","name":"\u5353\u8d8a\u96fb\u5b50\u5831","url":"https:\/\/readfi.news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/readfi.news\/#\/schema\/logo\/image\/","url":"https:\/\/readfi.news\/wp-content\/uploads\/2022\/04\/logo.jpg","contentUrl":"https:\/\/readfi.news\/wp-content\/uploads\/2022\/04\/logo.jpg","width":880,"height":322,"caption":"\u5353\u8d8a\u96fb\u5b50\u5831"},"image":{"@id":"https:\/\/readfi.news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/readfi.news"]}]}},"_links":{"self":[{"href":"https:\/\/readfi.news\/en\/wp-json\/wp\/v2\/tags\/5989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/readfi.news\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/readfi.news\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/readfi.news\/en\/wp-json\/wp\/v2\/posts?tags=5989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}